{"id":4573,"date":"2024-03-11T00:04:37","date_gmt":"2024-03-11T08:04:37","guid":{"rendered":"https:\/\/lidaglassware.com\/?p=4573"},"modified":"2024-03-11T00:04:37","modified_gmt":"2024-03-11T08:04:37","slug":"mini-glass-mug-for-don-julio","status":"publish","type":"post","link":"https:\/\/lidaglassware.com\/pt\/mini-glass-mug-for-don-julio\/","title":{"rendered":"Estudo de caso: elabora\u00e7\u00e3o de uma mini caneca de vidro exclusiva para Don Julio"},"content":{"rendered":"<p><strong>Vis\u00e3o geral<\/strong><\/p>\n<p>Don Julio \u00e9 uma marca renomada conhecida por sua tequila premium, que incorpora rica tradi\u00e7\u00e3o e qualidade. A Lida Glassware foi convidada para projetar e produzir uma mini caneca de vidro distinta que ressoasse com a imagem de prest\u00edgio de Don Julio.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Processo<\/strong><\/p>\n<p>Nosso cliente \u00e9 uma empresa de promo\u00e7\u00e3o internacional e premium no M\u00e9xico. Eles ganharam o evento do Don Julio com essa mini caneca de vidro. Discutimos o plano final e obtivemos aprova\u00e7\u00e3o. Isso era fazer caneca de vidro, depois fazer pintura preta incluindo logotipo Don Julio branco.<\/p>\n<p>Depois de confirmar todos os requisitos espec\u00edficos com o cliente, primeiramente fizemos uma arte de design para confirma\u00e7\u00e3o.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-4580\" src=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mug-mould8.24-300x246.jpg\" alt=\"Molde de caneca8.24\" width=\"489\" height=\"400\" srcset=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mug-mould8.24-300x246.jpg 300w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mug-mould8.24-768x629.jpg 768w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mug-mould8.24-15x12.jpg 15w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mug-mould8.24-600x491.jpg 600w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mug-mould8.24.jpg 800w\" sizes=\"(max-width: 489px) 100vw, 489px\" \/><\/p>\n<p>Ap\u00f3s obter a aprova\u00e7\u00e3o, iniciamos a produ\u00e7\u00e3o da caneca de vidro transparente. Como rotina normal, eles acompanhavam a produ\u00e7\u00e3o o tempo todo. Desde o momento em que todos os moldes foram equipados, at\u00e9 ao final em que todos os vidros foram finalizados. Este acompanhamento atento foi crucial para manter a integridade do produto final.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-4581\" src=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug-1024x683.jpg\" alt=\"Mini caneca de vidro transparente\" width=\"600\" height=\"400\" srcset=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug-1024x683.jpg 1024w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug-300x200.jpg 300w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug-768x512.jpg 768w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug-18x12.jpg 18w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug-600x400.jpg 600w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Clear-Mini-Glass-Mug.jpg 1200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>O pr\u00f3ximo passo foi fazer a pintura e fazer o Logotipo Donjulio. Na p\u00f3s-produ\u00e7\u00e3o, aplicamos cores e o logo Don Julio nos \u00f3culos, acrescentando o toque \u00fanico da marca. A etapa final envolveu o design de embalagens seguras e de marca para completar a experi\u00eancia, garantindo que cada pe\u00e7a fosse entregue em perfeitas condi\u00e7\u00f5es e pronta para impressionar.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-4582\" src=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production-1024x683.jpg\" alt=\"Produ\u00e7\u00e3o de mini canecas de vidro\" width=\"600\" height=\"400\" srcset=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production-1024x683.jpg 1024w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production-300x200.jpg 300w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production-768x512.jpg 768w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production-18x12.jpg 18w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production-600x400.jpg 600w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Mini-Glass-Mug-Production.jpg 1200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>A etapa final do processo de fabrica\u00e7\u00e3o foi o design e implementa\u00e7\u00e3o de embalagens personalizadas e seguras. Esta embalagem n\u00e3o foi pensada apenas para proteger o produto durante o transporte, mas tamb\u00e9m para melhorar a experi\u00eancia de unboxing, refor\u00e7ando assim o car\u00e1ter premium da marca e do presente.<\/p>\n<p>Depois de terminar todas as mercadorias, nosso pessoal de controle de qualidade fez a inspe\u00e7\u00e3o interna e enviou nosso relat\u00f3rio ao cliente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4583\" src=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug-1024x683.jpg\" alt=\"Relat\u00f3rio de inspe\u00e7\u00e3o de mini caneca de vidro\" width=\"600\" height=\"400\" srcset=\"https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug-1024x683.jpg 1024w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug-300x200.jpg 300w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug-768x512.jpg 768w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug-18x12.jpg 18w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug-600x400.jpg 600w, https:\/\/lidaglassware.com\/wp-content\/uploads\/2024\/03\/Inspection-Report-of-mini-glass-mug.jpg 1200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>Resultados e coment\u00e1rios<\/strong><\/p>\n<p>O lan\u00e7amento foi um sucesso. Recebemos excelentes coment\u00e1rios, com clientes elogiando o design e a qualidade dos \u00f3culos. Isso resultou em maior envolvimento e visibilidade da marca para Don Julio. As vendas aumentaram e o projeto foi destaque em diversos ve\u00edculos de comunica\u00e7\u00e3o, fortalecendo ainda mais o perfil da marca. No geral, a campanha demonstrou a efic\u00e1cia de brindes de marca bem elaborados no marketing.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Overview Don Julio is a renowned brand known for its premium tequila, embodying rich tradition and quality. Lida Glassware was approached to design and produce a distinctive mini glass mug that would resonate with Don Julio&#8217;s prestigious image. &nbsp; Process Our client is an international promotion and premium company in Mexico. They got the event [&hellip;]<\/p>","protected":false},"author":1,"featured_media":4579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[236],"tags":[237],"class_list":["post-4573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies","tag-case-study"],"_links":{"self":[{"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/posts\/4573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/comments?post=4573"}],"version-history":[{"count":0,"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/posts\/4573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/media\/4579"}],"wp:attachment":[{"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/media?parent=4573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/categories?post=4573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lidaglassware.com\/pt\/wp-json\/wp\/v2\/tags?post=4573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}